{"id":1609,"date":"2019-04-23T11:52:48","date_gmt":"2019-04-23T11:52:48","guid":{"rendered":"https:\/\/adpcosmetics.com\/?p=1609"},"modified":"2021-06-23T11:55:37","modified_gmt":"2021-06-23T11:55:37","slug":"llegamos-a-la-tierra-de-las-oportunidades","status":"publish","type":"post","link":"https:\/\/adpcosmetics.com\/es\/llegamos-a-la-tierra-de-las-oportunidades\/","title":{"rendered":"Llegamos a la \u00abTierra de las Oportunidades\u00bb"},"content":{"rendered":"<p style=\"text-align: center;\">En ADPCosmetics damos un nuevo salto para llevar nuestros productos a Estados Unidos, en concreto, al\u00a0<span class=\"negrita\">Supplier&#8217;s Day de Nueva York.<\/span><\/p>\n<h4 style=\"text-align: center;\">7-8 Mayo | Jacob K. Javits Convention Center (New York) | Stand 2012<\/h4>\n<p style=\"text-align: center;\">Son varios los motivos que han hecho que decidamos asistir a este evento, que adem\u00e1s, celebra su cuadrag\u00e9simo aniversario.<\/p>\n<p style=\"text-align: center;\">En primer lugar, es una gran oportunidad para abrirnos a un\u00a0<span class=\"negrita\">mercado que se declara todav\u00eda deficiente<\/span>\u00a0en cuanto a la oferta de alternativas para la creaci\u00f3n de productos solares. Ante esta situaci\u00f3n tanto\u00a0<span class=\"negrita\">nuestros filtros solares como pigmentos pueden ser la soluci\u00f3n<\/span>\u00a0que el mercado americano estaba esperando para poder hacer frente a sus necesidades de producci\u00f3n.<\/p>\n<p style=\"text-align: center;\">Por otro lado, hace poco llevamos a cabo el\u00a0<span class=\"negrita\">registro en la FDA,<\/span>\u00a0la agencia del gobierno de los Estados Unidos responsable de la regulaci\u00f3n de alimentos y medicamentos. Este \u00f3rgano existe para asegurar la seguridad de los consumidores y efectividad de los productos comercializados y\u00a0<span class=\"negrita\">contar con su registro es imprescindible de cara a poder crear relaciones comerciales en este nuevo mercado.<\/span><\/p>\n<p style=\"text-align: center;\">Es por todo ello, por lo que asistir\u00a0<span class=\"negrita\">al Supplier&#8217;s Day de Nueva York supone una gran oportunidad para ADPCosmetics,<\/span>\u00a0para darnos visibilidad, poder generar acuerdos de colaboraci\u00f3n para nuevos desarrollos o de distribuci\u00f3n.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En ADPCosmetics damos un nuevo salto para llevar nuestros productos a Estados Unidos, en concreto, al\u00a0Supplier&#8217;s Day de Nueva York. 7-8 Mayo | Jacob K. Javits Convention Center (New York) | Stand 2012 Son varios los motivos que han hecho que decidamos asistir a este evento, que adem\u00e1s, celebra su cuadrag\u00e9simo aniversario. En primer lugar, es una gran oportunidad para abrirnos a un\u00a0mercado que se declara todav\u00eda deficiente\u00a0en cuanto a la oferta de alternativas para la creaci\u00f3n de productos solares. Ante esta situaci\u00f3n tanto\u00a0nuestros filtros solares como pigmentos pueden ser la soluci\u00f3n\u00a0que el mercado americano estaba esperando para poder hacer frente a sus necesidades de producci\u00f3n. Por otro lado, hace poco llevamos a cabo el\u00a0registro en la FDA,\u00a0la agencia del gobierno de los Estados Unidos responsable de la regulaci\u00f3n de alimentos y medicamentos. Este \u00f3rgano [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":266,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/posts\/1609"}],"collection":[{"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/comments?post=1609"}],"version-history":[{"count":0,"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/posts\/1609\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/media\/266"}],"wp:attachment":[{"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/media?parent=1609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/categories?post=1609"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/adpcosmetics.com\/es\/wp-json\/wp\/v2\/tags?post=1609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}